{"id":7857,"date":"2018-09-07T09:06:40","date_gmt":"2018-09-07T07:06:40","guid":{"rendered":"http:\/\/giusseppe.net\/blog\/?p=7857"},"modified":"2018-09-05T17:13:39","modified_gmt":"2018-09-05T15:13:39","slug":"un-micro-aire-acondicionado","status":"publish","type":"post","link":"https:\/\/www.giusseppe.net\/blog\/archivo\/2018\/09\/07\/un-micro-aire-acondicionado\/","title":{"rendered":"Un \u00abmicro\u00bb aire acondicionado"},"content":{"rendered":"<p>Una muestra de c\u00f3mo enfriar el aire con medios m\u00e1s que precarios:<\/p>\n<p>Tomar dos botellas de pl\u00e1stico, llenarlas de agua, meterlas en un congelador (que por supuesto gasta energ\u00eda en enfriarlas, as\u00ed que no pensemos que no consumimos nada). <\/p>\n<p>Cuando se vaya a usar, poner un plato o contenedor para que el agua de condensaci\u00f3n que se formar\u00e1 en torno a las botellas congeladas tenga donde gotear. Poner las botellas delante de un ventilador que al ir moviendo el aire en esa direcci\u00f3n se ir\u00e1 enfriando (sin lograr temperaturas verdaderamente bajas)<\/p>\n<div id='gallery-1' class='gallery galleryid-7857 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.giusseppe.net\/blog\/wp-content\/uploads\/2018\/09\/IMG_20180619_175848.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/www.giusseppe.net\/blog\/wp-content\/uploads\/2018\/09\/IMG_20180619_175848-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.giusseppe.net\/blog\/wp-content\/uploads\/2018\/09\/IMG_20180619_175848-169x300.jpg 169w, https:\/\/www.giusseppe.net\/blog\/wp-content\/uploads\/2018\/09\/IMG_20180619_175848-768x1365.jpg 768w, https:\/\/www.giusseppe.net\/blog\/wp-content\/uploads\/2018\/09\/IMG_20180619_175848-338x600.jpg 338w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.giusseppe.net\/blog\/wp-content\/uploads\/2018\/09\/IMG_20180619_175853.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/www.giusseppe.net\/blog\/wp-content\/uploads\/2018\/09\/IMG_20180619_175853-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.giusseppe.net\/blog\/wp-content\/uploads\/2018\/09\/IMG_20180619_175853-169x300.jpg 169w, https:\/\/www.giusseppe.net\/blog\/wp-content\/uploads\/2018\/09\/IMG_20180619_175853-768x1365.jpg 768w, https:\/\/www.giusseppe.net\/blog\/wp-content\/uploads\/2018\/09\/IMG_20180619_175853-338x600.jpg 338w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.giusseppe.net\/blog\/wp-content\/uploads\/2018\/09\/IMG_20180619_175840.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/www.giusseppe.net\/blog\/wp-content\/uploads\/2018\/09\/IMG_20180619_175840-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.giusseppe.net\/blog\/wp-content\/uploads\/2018\/09\/IMG_20180619_175840-169x300.jpg 169w, https:\/\/www.giusseppe.net\/blog\/wp-content\/uploads\/2018\/09\/IMG_20180619_175840-768x1365.jpg 768w, https:\/\/www.giusseppe.net\/blog\/wp-content\/uploads\/2018\/09\/IMG_20180619_175840-338x600.jpg 338w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Lo estuve usando la \u00faltima semana de junio y algo incid\u00eda en hacer soportable mi estancia en mi lugar de trabajo, sin tener que recurrir a un sofisticado aparatito con instalaci\u00f3n incluida.<\/p>\n<p>No es una maravilla, pero es una maravilla. \u00bfSe entiende?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una muestra de c\u00f3mo enfriar el aire con medios m\u00e1s que precarios: Tomar dos botellas de pl\u00e1stico, llenarlas de agua, meterlas en un congelador (que por supuesto gasta energ\u00eda en enfriarlas, as\u00ed que no pensemos que no consumimos nada). Cuando se vaya a usar, poner un plato o contenedor para que el agua de condensaci\u00f3n &#8230; <a title=\"Un \u00abmicro\u00bb aire acondicionado\" class=\"read-more\" href=\"https:\/\/www.giusseppe.net\/blog\/archivo\/2018\/09\/07\/un-micro-aire-acondicionado\/\">Read more<span class=\"screen-reader-text\">Un \u00abmicro\u00bb aire acondicionado<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[94],"tags":[207,72,87],"class_list":["post-7857","post","type-post","status-publish","format-standard","hentry","category-fotografia","tag-ecologia","tag-mercado","tag-modo-de-vida"],"_links":{"self":[{"href":"https:\/\/www.giusseppe.net\/blog\/wp-json\/wp\/v2\/posts\/7857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.giusseppe.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.giusseppe.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.giusseppe.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.giusseppe.net\/blog\/wp-json\/wp\/v2\/comments?post=7857"}],"version-history":[{"count":1,"href":"https:\/\/www.giusseppe.net\/blog\/wp-json\/wp\/v2\/posts\/7857\/revisions"}],"predecessor-version":[{"id":7861,"href":"https:\/\/www.giusseppe.net\/blog\/wp-json\/wp\/v2\/posts\/7857\/revisions\/7861"}],"wp:attachment":[{"href":"https:\/\/www.giusseppe.net\/blog\/wp-json\/wp\/v2\/media?parent=7857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.giusseppe.net\/blog\/wp-json\/wp\/v2\/categories?post=7857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.giusseppe.net\/blog\/wp-json\/wp\/v2\/tags?post=7857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}